{"id":6055,"date":"2019-01-31T14:09:51","date_gmt":"2019-01-31T14:09:51","guid":{"rendered":"http:\/\/www.pladebarrisdelaflorida.cat\/?p=6055"},"modified":"2019-01-31T14:09:51","modified_gmt":"2019-01-31T14:09:51","slug":"el-ayuntamiento-pone-en-marcha-una-decena-de-acciones-formativas-gratuitas-para-el-primer-semestre-del-2019","status":"publish","type":"post","link":"https:\/\/www.pladebarrisdelaflorida.cat\/es\/el-ayuntamiento-pone-en-marcha-una-decena-de-acciones-formativas-gratuitas-para-el-primer-semestre-del-2019\/","title":{"rendered":"EL AYUNTAMIENTO PONE EN MARCHA UNA DECENA DE ACCIONES FORMATIVAS GRATUITAS PARA EL PRIMER SEMESTRE DEL 2019"},"content":{"rendered":"<div class=\"post-meta\"><\/div>\n<ul>\n<li><span style=\"color: #ff00ff;\"><em>La oferta incluye cursos, talleres formativos y como novedad dos master class<\/em><\/span><\/li>\n<li><span style=\"color: #ff00ff;\"><em>Se contin\u00faa apostando por ofrecer formaci\u00f3n a personas desempleadas mayores de 45 a\u00f1os, los perfiles m\u00e1s habituales de la bolsa de trabajo municipal, as\u00ed como acciones espec\u00edficas para empresarios<\/em><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<div class=\"entry-content\">\n<p><span class=\"tlid-translation translation\">La concejal\u00eda de Impulso Econ\u00f3mico y Empleo del Ayuntamiento de Mont-roig del Camp ha presentado la programaci\u00f3n formativa de 2019, correspondiente al primer semestre del a\u00f1o. En concreto son una decena de cursos, talleres formativos y dos master class, una de las novedades de esta edici\u00f3n. Todo ello para mejorar la capacitaci\u00f3n y cualificaci\u00f3n profesional de la poblaci\u00f3n as\u00ed como para favorecer la inserci\u00f3n laboral de las personas que se encuentran en situaci\u00f3n de desempleo.<a href=\"http:\/\/www.pladebarrisdelaflorida.cat\/wp-content\/uploads\/2019\/01\/ofertaformativa-1-355x500.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6052 alignright\" src=\"http:\/\/www.pladebarrisdelaflorida.cat\/wp-content\/uploads\/2019\/01\/ofertaformativa-1-355x500.jpg\" alt=\"\" width=\"336\" height=\"475\" \/><\/a><\/span><\/p>\n<p>En esta ocasi\u00f3n se contin\u00faa apostando por la formaci\u00f3n espec\u00edfica para personas desempleadas mayores de 45 a\u00f1os, con el fin de promover la formaci\u00f3n y empleo de este colectivo. En concreto se ha programado un curso de ayudante\/a de cocina, que tendr\u00e1 lugar en el Institut Escola d\u2019Hoteleria de Cambrils los meses de marzo y abril.<\/p>\n<p>Tambi\u00e9n se han tenido en cuenta algunos de los principales perfiles de la bolsa de trabajo municipal para ofrecer cursos como el de controlador de acceso que tendr\u00e1 lugar del 4 al 20 de marzo y capacitar\u00e1 al alumnado obtener la habilitaci\u00f3n de la Generalitat de Catalu\u00f1a, as\u00ed como el de atenci\u00f3n sociosanitaria a personas en el domicilio, que tendr\u00e1 lugar los meses de abril y mayo.<\/p>\n<p>En cuanto a cursos, se vuelven a programar el de manipulador de alimentos, alergias e intolerancias alimentarias, por ser uno de los m\u00e1s demandados, en una sesi\u00f3n en Mont-roig y otra en Miami Platja.<\/p>\n<p>Las master class de t\u00e9cnicas de escaparatismo son una de las novedades de esta edici\u00f3n y destacan porque tendr\u00e1n lugar en escaparates de tiendas reales, de Mont-roig y de Miami Platja. Tambi\u00e9n el curso de fotograf\u00eda destaca porque va destinado principalmente a promocionar oficios, productos o establecimientos y porque incluye pr\u00e1cticas en tiendas reales.<\/p>\n<p>En esta edici\u00f3n se mantienen los talleres dirigidos a empresarios y emprendedores. As\u00ed, se ofrecer\u00e1n sesiones formativas de dos horas de tem\u00e1ticas diversas como Instagram para empresas, creaci\u00f3n de cartas y men\u00fas y buena y mala praxis en la gesti\u00f3n de aplicaciones tur\u00edsticas.<\/p>\n<p><span style=\"color: #993366;\">Toda la oferta formativa es gratuita<\/span><\/p>\n<p>Los cursos son gratuitos y tienen las plazas limitadas a un m\u00e1ximo de 25 personas. La Concejal\u00eda de Impulso Econ\u00f3mico y Empleo se reserva el derecho de anular o posponer alguno de los cursos ofrecidos si el n\u00famero de personas inscritas es inferior a 10 alumnos.<\/p>\n<p>Se impondr\u00e1 una fianza a las personas que se inscriban a los cursos, a fin de garantizar su asistencia (excepto el curso de manipulador\/a de alimentos). En cuanto a los talleres formativos y las master class est\u00e1n exentos de fianza. Al finalizar la formaci\u00f3n, si se ha asistido a un m\u00ednimo del 80% de las horas del curso, el usuario\/a podr\u00e1 solicitar el retorno de la fianza.<\/p>\n<p>Adem\u00e1s, los alumnos que lo deseen podr\u00e1n hacer uso, tambi\u00e9n de forma gratuita, del autob\u00fas municipal para desplazarse entre Mont-roig y Miami Platja y asistir a las acciones formativas, previa solicitud al departamento de Impulso Econ\u00f3mico.<\/p>\n<p>Las inscripciones se pueden hacer a trav\u00e9s de la sede electr\u00f3nica, en las oficinas de l\u2019Espai o a trav\u00e9s del registro de entrada de las Oficinas Municipales de Atenci\u00f3n a la Ciudadan\u00eda.<\/p>\n<p>Consulta el cat\u00e1logo formativo:<\/p>\n<p><a class=\"ext-link wpel-icon-right\" href=\"https:\/\/mont-roig.cat\/wp-content\/uploads\/Programa-de-formacio%CC%81-2019-Impuls-Econ%C3%B2mic.pdf\" target=\"_blank\" rel=\"noopener nofollow external noreferrer\" data-wpel-link=\"external\">Enlace<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La oferta incluye cursos, talleres formativos y como novedad dos master class Se contin\u00faa apostando por ofrecer formaci\u00f3n a personas desempleadas mayores de 45 a\u00f1os, los perfiles m\u00e1s habituales de la bolsa de trabajo municipal, as\u00ed como acciones espec\u00edficas para empresarios &nbsp; La concejal\u00eda de Impulso Econ\u00f3mico y Empleo del Ayuntamiento de Mont-roig del Camp ha presentado la programaci\u00f3n formativa de 2019, correspondiente al primer semestre del a\u00f1o. En concreto son una decena de cursos, talleres formativos y dos master class, una de las novedades de esta edici\u00f3n. Todo ello para mejorar la capacitaci\u00f3n y cualificaci\u00f3n profesional de la poblaci\u00f3n as\u00ed como para favorecer la inserci\u00f3n laboral de las personas que se encuentran en situaci\u00f3n de desempleo. En esta ocasi\u00f3n se contin\u00faa apostando por la formaci\u00f3n espec\u00edfica para personas desempleadas mayores de 45 a\u00f1os, con el fin de promover la formaci\u00f3n y empleo de este colectivo. En concreto se ha programado un curso de ayudante\/a de cocina, que tendr\u00e1 lugar en el Institut Escola d\u2019Hoteleria de Cambrils los meses de marzo y abril. Tambi\u00e9n se han tenido en cuenta algunos de los principales perfiles de la bolsa de trabajo municipal para ofrecer cursos como el de controlador de acceso que&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":6052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general-es"],"_links":{"self":[{"href":"https:\/\/www.pladebarrisdelaflorida.cat\/es\/wp-json\/wp\/v2\/posts\/6055\/"}],"collection":[{"href":"https:\/\/www.pladebarrisdelaflorida.cat\/es\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.pladebarrisdelaflorida.cat\/es\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.pladebarrisdelaflorida.cat\/es\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pladebarrisdelaflorida.cat\/es\/wp-json\/wp\/v2\/comments\/?post=6055"}],"version-history":[{"count":1,"href":"https:\/\/www.pladebarrisdelaflorida.cat\/es\/wp-json\/wp\/v2\/posts\/6055\/revisions\/"}],"predecessor-version":[{"id":6056,"href":"https:\/\/www.pladebarrisdelaflorida.cat\/es\/wp-json\/wp\/v2\/posts\/6055\/revisions\/6056\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pladebarrisdelaflorida.cat\/es\/wp-json\/wp\/v2\/media\/6052\/"}],"wp:attachment":[{"href":"https:\/\/www.pladebarrisdelaflorida.cat\/es\/wp-json\/wp\/v2\/media\/?parent=6055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pladebarrisdelaflorida.cat\/es\/wp-json\/wp\/v2\/categories\/?post=6055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pladebarrisdelaflorida.cat\/es\/wp-json\/wp\/v2\/tags\/?post=6055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}